{"id":2862,"date":"2021-05-26T16:34:35","date_gmt":"2021-05-26T20:34:35","guid":{"rendered":"https:\/\/retourautravail.irsst.qc.ca\/irsst?p=2862"},"modified":"2024-10-15T17:17:41","modified_gmt":"2024-10-15T21:17:41","slug":"appendix-4-j-vignette-tmc-intense-stress-at-work","status":"publish","type":"post","link":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/","title":{"rendered":"Appendix 4.J &#8211; CMD (severe work stress) vignette"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false},"class_list":["post-2862","post","type-post","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail\" \/>\n<meta property=\"og:url\" content=\"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;incapacit\u00e9 et le retour au travail\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-26T20:34:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T21:17:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/retourautravail.irsst.qc.ca\/wp-content\/uploads\/2021\/11\/RAT-actu-social.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ga\u00e9tan Boucher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/\"},\"author\":{\"name\":\"Ga\u00e9tan Boucher\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/#\\\/schema\\\/person\\\/08ab86e32919d5724e53f5403e57869b\"},\"headline\":\"Appendix 4.J &#8211; CMD (severe work stress) vignette\",\"datePublished\":\"2021-05-26T20:34:35+00:00\",\"dateModified\":\"2024-10-15T21:17:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/\"},\"wordCount\":8,\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/\",\"url\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/\",\"name\":\"Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/#website\"},\"datePublished\":\"2021-05-26T20:34:35+00:00\",\"dateModified\":\"2024-10-15T21:17:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/#\\\/schema\\\/person\\\/08ab86e32919d5724e53f5403e57869b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/non-classifiee\\\/appendix-4-j-vignette-tmc-intense-stress-at-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Appendix 4.J &#8211; CMD (severe work stress) vignette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/#website\",\"url\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/\",\"name\":\"L&#039;incapacit\u00e9 et le retour au travail\",\"description\":\"Une source d\u2019information cr\u00e9dible pour les meilleures pratiques lors de la mise en place des processus de pr\u00e9vention de l\u2019 incapacit\u00e9 au travail et d\u2019un retour au travail sain et durable.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/retourautravail.irsst.qc.ca\\\/#\\\/schema\\\/person\\\/08ab86e32919d5724e53f5403e57869b\",\"name\":\"Ga\u00e9tan Boucher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g\",\"caption\":\"Ga\u00e9tan Boucher\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/","og_locale":"en_US","og_type":"article","og_title":"Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail","og_url":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/","og_site_name":"L&#039;incapacit\u00e9 et le retour au travail","article_published_time":"2021-05-26T20:34:35+00:00","article_modified_time":"2024-10-15T21:17:41+00:00","og_image":[{"width":1280,"height":672,"url":"https:\/\/retourautravail.irsst.qc.ca\/wp-content\/uploads\/2021\/11\/RAT-actu-social.png","type":"image\/png"}],"author":"Ga\u00e9tan Boucher","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/#article","isPartOf":{"@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/"},"author":{"name":"Ga\u00e9tan Boucher","@id":"https:\/\/retourautravail.irsst.qc.ca\/#\/schema\/person\/08ab86e32919d5724e53f5403e57869b"},"headline":"Appendix 4.J &#8211; CMD (severe work stress) vignette","datePublished":"2021-05-26T20:34:35+00:00","dateModified":"2024-10-15T21:17:41+00:00","mainEntityOfPage":{"@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/"},"wordCount":8,"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/","url":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/","name":"Appendix 4.J - CMD (severe work stress) vignette &#8211; L&#039;incapacit\u00e9 et le retour au travail","isPartOf":{"@id":"https:\/\/retourautravail.irsst.qc.ca\/#website"},"datePublished":"2021-05-26T20:34:35+00:00","dateModified":"2024-10-15T21:17:41+00:00","author":{"@id":"https:\/\/retourautravail.irsst.qc.ca\/#\/schema\/person\/08ab86e32919d5724e53f5403e57869b"},"breadcrumb":{"@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/retourautravail.irsst.qc.ca\/en\/non-classifiee\/appendix-4-j-vignette-tmc-intense-stress-at-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/retourautravail.irsst.qc.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Appendix 4.J &#8211; CMD (severe work stress) vignette"}]},{"@type":"WebSite","@id":"https:\/\/retourautravail.irsst.qc.ca\/#website","url":"https:\/\/retourautravail.irsst.qc.ca\/","name":"L&#039;incapacit\u00e9 et le retour au travail","description":"Une source d\u2019information cr\u00e9dible pour les meilleures pratiques lors de la mise en place des processus de pr\u00e9vention de l\u2019 incapacit\u00e9 au travail et d\u2019un retour au travail sain et durable.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/retourautravail.irsst.qc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/retourautravail.irsst.qc.ca\/#\/schema\/person\/08ab86e32919d5724e53f5403e57869b","name":"Ga\u00e9tan Boucher","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26756d0e5d308557aeb966fdc2a9887a35d49f3d309295d9986c027fed988ea0?s=96&d=mm&r=g","caption":"Ga\u00e9tan Boucher"}}]}},"_links":{"self":[{"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/posts\/2862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/comments?post=2862"}],"version-history":[{"count":6,"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/posts\/2862\/revisions"}],"predecessor-version":[{"id":4095,"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/posts\/2862\/revisions\/4095"}],"wp:attachment":[{"href":"https:\/\/retourautravail.irsst.qc.ca\/en\/wp-json\/wp\/v2\/media?parent=2862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}